{"id":11861,"date":"2024-06-19T17:57:36","date_gmt":"2024-06-19T15:57:36","guid":{"rendered":"https:\/\/copterweb.de\/wordpress\/wp-content\/uploads\/ILA24_27.jpg"},"modified":"2024-06-19T17:57:36","modified_gmt":"2024-06-19T15:57:36","slug":"ila24_27","status":"inherit","type":"attachment","link":"https:\/\/copterweb.de\/wordpress\/ila-berlin-schliesst-mit-besucherplus-ein-rueckblick\/ila24_27\/","title":{"rendered":"<span class=\"caps\">ILA24_27<\/span>"},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0},"description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/copterweb.de\/wordpress\/wp-content\/uploads\/ILA24_27.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/copterweb.de\/wordpress\/wp-content\/uploads\/ILA24_27-300x200.jpg\" class=\"attachment-medium size-medium\" alt srcset=\"https:\/\/copterweb.de\/wordpress\/wp-content\/uploads\/ILA24_27-300x200.jpg 300w, https:\/\/copterweb.de\/wordpress\/wp-content\/uploads\/ILA24_27-1024x683.jpg 1024w, https:\/\/copterweb.de\/wordpress\/wp-content\/uploads\/ILA24_27-768x512.jpg 768w, https:\/\/copterweb.de\/wordpress\/wp-content\/uploads\/ILA24_27.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\"><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1200,"height":800,"file":"ILA24_27.jpg","filesize":290729,"sizes":{"medium":{"file":"ILA24_27-300x200.jpg","width":300,"height":200,"filesize":38925,"mime_type":"image\/jpeg","source_url":"https:\/\/copterweb.de\/wordpress\/wp-content\/uploads\/ILA24_27-300x200.jpg"},"large":{"file":"ILA24_27-1024x683.jpg","width":1024,"height":683,"filesize":118967,"mime_type":"image\/jpeg","source_url":"https:\/\/copterweb.de\/wordpress\/wp-content\/uploads\/ILA24_27-1024x683.jpg"},"thumbnail":{"file":"ILA24_27-150x150.jpg","width":150,"height":150,"filesize":31964,"mime_type":"image\/jpeg","source_url":"https:\/\/copterweb.de\/wordpress\/wp-content\/uploads\/ILA24_27-150x150.jpg"},"medium_large":{"file":"ILA24_27-768x512.jpg","width":768,"height":512,"filesize":83049,"mime_type":"image\/jpeg","source_url":"https:\/\/copterweb.de\/wordpress\/wp-content\/uploads\/ILA24_27-768x512.jpg"},"post-thumbnail":{"file":"ILA24_27-940x198.jpg","width":940,"height":198,"filesize":65848,"mime_type":"image\/jpeg","source_url":"https:\/\/copterweb.de\/wordpress\/wp-content\/uploads\/ILA24_27-940x198.jpg"},"full":{"file":"ILA24_27.jpg","width":1200,"height":800,"mime_type":"image\/jpeg","source_url":"https:\/\/copterweb.de\/wordpress\/wp-content\/uploads\/ILA24_27.jpg"}},"image_meta":{"aperture":"4.5","credit":"Picasa","camera":"DSC-RX10M4","caption":"","created_timestamp":"1717865410","copyright":"","focal_length":"8.8","iso":"100","shutter_speed":"0.001","title":"","orientation":"0","keywords":[]}},"post":11810,"source_url":"https:\/\/copterweb.de\/wordpress\/wp-content\/uploads\/ILA24_27.jpg","_links":{"self":[{"href":"https:\/\/copterweb.de\/wordpress\/wp-json\/wp\/v2\/media\/11861"}],"collection":[{"href":"https:\/\/copterweb.de\/wordpress\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/copterweb.de\/wordpress\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/copterweb.de\/wordpress\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/copterweb.de\/wordpress\/wp-json\/wp\/v2\/comments?post=11861"}]}}